{"id":96,"date":"2026-08-27T02:36:07","date_gmt":"2026-08-27T00:36:07","guid":{"rendered":"https:\/\/campermax.websmwinner.com\/?page_id=96"},"modified":"2026-08-29T02:49:05","modified_gmt":"2026-08-29T00:49:05","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/campermax.websmwinner.com\/en\/politica-de-cookies\/","title":{"rendered":"Cookies policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"96\" class=\"elementor elementor-96\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6bcbb8 e-flex e-con-boxed e-con e-parent\" data-id=\"c6bcbb8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-43f34f35 e-con-full e-flex e-con e-child\" data-id=\"43f34f35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-520d9e71 elementor-widget elementor-widget-heading\" data-id=\"520d9e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edticas De Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d2323ee elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1d2323ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-home\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M280.37 148.26L96 300.11V464a16 16 0 0 0 16 16l112.06-.29a16 16 0 0 0 15.92-16V368a16 16 0 0 1 16-16h64a16 16 0 0 1 16 16v95.64a16 16 0 0 0 16 16.05L464 480a16 16 0 0 0 16-16V300L295.67 148.26a12.19 12.19 0 0 0-15.3 0zM571.6 251.47L488 182.56V44.05a12 12 0 0 0-12-12h-56a12 12 0 0 0-12 12v72.61L318.47 43a48 48 0 0 0-61 0L4.34 251.47a12 12 0 0 0-1.6 16.9l25.5 31A12 12 0 0 0 45.15 301l235.22-193.74a12.19 12.19 0 0 1 15.3 0L530.9 301a12 12 0 0 0 16.9-1.6l25.5-31a12 12 0 0 0-1.7-16.93z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edticas De Cookies<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6534f693 e-con-full e-flex e-con e-parent\" data-id=\"6534f693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-478e41ed e-con-full e-flex e-con e-child\" data-id=\"478e41ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d4549ec e-con-full e-flex e-con e-child\" data-id=\"d4549ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4de573 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1d4de573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"cli_pg_page_contaner\"><h3><strong>Sobre esta pol\u00edtica de cookies<\/strong><\/h3><div>Esta Pol\u00edtica de cookies explica qu\u00e9 son las cookies y c\u00f3mo las usamos. Debe leer esta pol\u00edtica para comprender qu\u00e9 son las cookies, c\u00f3mo las utilizamos, los tipos de cookies que utilizamos, es decir, la informaci\u00f3n que recopilamos utilizando cookies y c\u00f3mo se utiliza esa informaci\u00f3n y c\u00f3mo controlar las preferencias de cookies.<\/div><div>\u00a0<\/div><div>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo usamos, almacenamos y mantenemos seguros sus datos personales, consulte nuestra\u00a0<a href=\"https:\/\/www.specialcarslasramblas.es\/politica-de-privacidad\/\">Privacy Policy<\/a>.<\/div><div>\u00a0<\/div><div>En cualquier momento puede cambiar o retirar su consentimiento de la Declaraci\u00f3n de cookies en nuestro sitio web.<\/div><div>\u00a0<\/div><div>Obtenga m\u00e1s informaci\u00f3n sobre qui\u00e9nes somos, c\u00f3mo puede contactarnos y c\u00f3mo procesamos los datos personales en nuestra\u00a0<a href=\"https:\/\/www.specialcarslasramblas.es\/politica-de-privacidad\/\">Privacy Policy<\/a>.<\/div><div>\u00a0<\/div><div>Su consentimiento se aplica a los siguientes dominios:\u00a0<a href=\"https:\/\/specialcarslasramblas.es\/\">specialcarslasramblas.es<\/a><\/div><\/div><div>\u00a0<\/div><div class=\"cli_pg_page_contaner\"><div>Tu estado actual: Consentimiento aceptado. <a class=\"cli_manage_current_consent\">Gestiona tu consentimiento.<\/a><\/div><div><div>\u00a0<\/div><\/div><strong>\u00bfQu\u00e9 son las cookies?<\/strong><\/div><div class=\"cli_pg_page_contaner\"><div>\u00a0<\/div><div>Una cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/div><h3><strong>\u00bfQu\u00e9 tipos de cookies utiliza esta p\u00e1gina web?<\/strong><\/h3><p><strong>&#8211; Cookies de an\u00e1lisis<\/strong>: Son aqu\u00e9llas que bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ello se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos.<\/p><p>Lista de cookies utilizadas en su sitio web:<\/p><table class=\"cookielawinfo-row-cat-table cookielawinfo-classic\"><thead><tr><th class=\"cookielawinfo-column-1\">COOKIE<\/th><th class=\"cookielawinfo-column-4\">DESCRIPCI\u00d3N<\/th><\/tr><\/thead><tbody><tr class=\"cookielawinfo-row\"><td class=\"cookielawinfo-column-1\">Google Analytics<\/td><td class=\"cookielawinfo-column-4\">Cookie para estudio de audiencia a trav\u00e9s de la plataforma de Google Analytics.<\/td><\/tr><\/tbody><\/table><h3>\u00a0<\/h3><h3><strong>\u00bfC\u00f3mo puedo controlar mis preferencias sobre cookies?<\/strong><\/h3><div>Si decide cambiar sus preferencias m\u00e1s adelante durante su sesi\u00f3n de navegaci\u00f3n, puede hacer clic en la pesta\u00f1a \u201cPol\u00edtica de privacidad y cookies\u201d en su pantalla. Esto mostrar\u00e1 nuevamente el aviso de consentimiento que le permitir\u00e1 cambiar sus preferencias o retirar su consentimiento por completo.<\/div><div>\u00a0<\/div><div>Adem\u00e1s de esto, cada navegador proporcionan diferentes m\u00e9todos para bloquear y eliminar las cookies utilizadas por los sitios web. Puede cambiar la configuraci\u00f3n de su navegador para bloquear \/ eliminar las cookies.<\/div><div>\u00a0<\/div><div>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo administrar y eliminar cookies, visite\u00a0<a href=\"http:\/\/wikipedia.org\/\">wikipedia.org<\/a>,\u00a0<a href=\"http:\/\/www.allaboutcookies.org\/\">www.allaboutcookies.org<\/a>.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edticas De Cookies Inicio Pol\u00edticas De Cookies Sobre esta pol\u00edtica de cookies Esta Pol\u00edtica de cookies explica qu\u00e9 son las cookies y c\u00f3mo las usamos. Debe leer esta pol\u00edtica para comprender qu\u00e9 son las cookies, c\u00f3mo las utilizamos, los tipos de cookies que utilizamos, es decir, la informaci\u00f3n que recopilamos utilizando cookies y c\u00f3mo se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-96","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/pages\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":10,"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"predecessor-version":[{"id":497,"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/pages\/96\/revisions\/497"}],"wp:attachment":[{"href":"https:\/\/campermax.websmwinner.com\/en\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}