{"id":98,"date":"2026-08-27T02:36:40","date_gmt":"2026-08-27T00:36:40","guid":{"rendered":"https:\/\/campermax.websmwinner.com\/?page_id=98"},"modified":"2026-08-29T02:42:48","modified_gmt":"2026-08-29T00:42:48","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/campermax.websmwinner.com\/fr\/politica-de-privacidad\/","title":{"rendered":"politique de confidentialit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"98\" class=\"elementor elementor-98\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8c234d e-flex e-con-boxed e-con e-parent\" data-id=\"6c8c234d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47c94550 e-con-full e-flex e-con e-child\" data-id=\"47c94550\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16bde2b9 elementor-widget elementor-widget-heading\" data-id=\"16bde2b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edticas De Privacidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6658b8b2 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6658b8b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-home\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M280.37 148.26L96 300.11V464a16 16 0 0 0 16 16l112.06-.29a16 16 0 0 0 15.92-16V368a16 16 0 0 1 16-16h64a16 16 0 0 1 16 16v95.64a16 16 0 0 0 16 16.05L464 480a16 16 0 0 0 16-16V300L295.67 148.26a12.19 12.19 0 0 0-15.3 0zM571.6 251.47L488 182.56V44.05a12 12 0 0 0-12-12h-56a12 12 0 0 0-12 12v72.61L318.47 43a48 48 0 0 0-61 0L4.34 251.47a12 12 0 0 0-1.6 16.9l25.5 31A12 12 0 0 0 45.15 301l235.22-193.74a12.19 12.19 0 0 1 15.3 0L530.9 301a12 12 0 0 0 16.9-1.6l25.5-31a12 12 0 0 0-1.7-16.93z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Commencer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edticas De Privacidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-309d0c4e e-con-full e-flex e-con e-parent\" data-id=\"309d0c4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-51f748ae e-con-full e-flex e-con e-child\" data-id=\"51f748ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-383dbf12 e-con-full e-flex e-con e-child\" data-id=\"383dbf12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6994fc7d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6994fc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La presente \u201cPol\u00edtica de Privacidad\u201d recoge las reglas que rigen la recogida y tratamiento de datos personales por parte de NEGOCAR EXCLUSIVE SLU y garantiza que estas labores de recogida y tratamiento de datos cumplir\u00e1, en todo momento, cumpliendo en materia de protecci\u00f3n de datos de car\u00e1cter personal lo establecido en el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo de 27 de Abril de 2016 y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales.<\/p><p><strong>En nuestra Pol\u00edtica de Privacidad:<\/strong><\/p><p>1) Respetamos su privacidad y sus elecciones.<\/p><p>2) La privacidad y la seguridad de sus datos est\u00e1n incorporadas a nuestra pol\u00edtica.<\/p><p>3) Enviamos comunicaciones de marketing a menos que se soliciten que se anule.<\/p><p>4) Nunca ofrecemos ni cedemos sus datos, sin su consentimiento expreso.<\/p><p>5) Asumimos un compromiso de transparencia sobre el uso de sus datos.<\/p><p>6) No utilizamos sus datos sin haberle informado ni haber solicitado su consentimiento.<\/p><p>7) Respetamos sus derechos seg\u00fan lo establecido en la normativa y de acuerdo con nuestras propias responsabilidades legales y operativas.<\/p><p>Para obtener m\u00e1s informaci\u00f3n acerca de nuestras pr\u00e1cticas de privacidad, a continuaci\u00f3n, establecemos qu\u00e9 tipos de datos personales podemos recabar o mantener sobre usted, c\u00f3mo podemos usarlos, con qui\u00e9n podemos compartirlos, c\u00f3mo los protegemos, y c\u00f3mo puede ejercitar sus derechos respecto de dichos datos.<\/p><p>Cuando comparte sus datos personales con nosotros o cuando recabamos datos personales sobre usted, los usamos de acuerdo con esta Pol\u00edtica de Privacidad (en adelante, la \u201cPol\u00edtica\u201d). Si tiene alguna pregunta o inquietud sobre sus datos personales, cont\u00e1ctenos en\u00a0Antonio Mar\u00eda Manrique n\u00ba 26en Las Palmas de G.C..<\/p><h3><strong>\u00bfQUI\u00c9NES SOMOS?<\/strong><\/h3><p>NEGOCAR EXCLUSIVE SLU, con domicilio en Antonio Mar\u00eda Manrique n\u00ba 26en Las Palmas de G.C. con NIF B76272483 es responsable de los datos personales que usted comparte con nosotros. Por tanto, NEGOCAR EXCLUSIVE SLU es el responsable del tratamiento de datos a los efectos de la normativa aplicable sobre protecci\u00f3n de datos.<\/p><h3><strong>DATOS PERSONALES<\/strong><\/h3><p>Se entiende como Datos Personales a cualquier informaci\u00f3n o datos que pueda identificarlo directamente (por ejemplo, su nombre o apellidos) o indirectamente (por ejemplo, su documento nacional de identidad o D.N.I.). Los Datos Personales incluyen informaci\u00f3n tal como el correo electr\u00f3nico\/ direcciones postales particulares \/ tel\u00e9fono m\u00f3vil, nombres de usuario, im\u00e1genes de perfil, preferencias personales, contenido generado por el usuario, entre otros.Esta Pol\u00edtica cubre todos los datos personales recopilados y utilizados por NEGOCAR EXCLUSIVE SLU.<\/p><h3><strong>RECOGIDA DE DATOS PERSONALES Y FINALIDADES DEL TRATAMIENTO<\/strong><\/h3><p>Recuerde que antes de empezar a utilizar cualquiera de nuestros servicios o funcionalidades, deber\u00e1 leer esta Pol\u00edtica. El hecho de no facilitar cierta informaci\u00f3n se\u00f1alada como obligatoria, puede conllevar que no sea posible gestionar su registro como usuario o el uso de determinadas funcionalidades o servicios disponibles.<\/p><h4><strong>\u00bfQu\u00e9 datos suyos podemos recabar?<\/strong><\/h4><p>Podemos recabar o recibir sus datos a trav\u00e9s de nuestros sitios web, formularios, aplicaciones, dispositivos, entre otros. En algunos casos, usted nos facilita sus Datos Personales directamente (por ejemplo, cuando se pone en contacto con nosotros), en otros casos los recabamos nosotros (por ejemplo, usando cookies para comprender c\u00f3mo usa nuestros sitios web) o, en otras ocasiones, de manera indirecta cuando recibimos sus datos de otros terceros, incluidas otras entidades del asociadas a NEGOCAR EXCLUSIVE SLU.<\/p><h4><strong>\u00bfCu\u00e1l es la base legal para el Tratamiento de sus Datos Personales?<\/strong><\/h4><p>&#8211; Su consentimiento<\/p><p>&#8211; Nuestro inter\u00e9s leg\u00edtimo, que puede ser:<\/p><ul><li>Permitir el funcionamiento de nuestro sitio web \/ aplicaciones a trav\u00e9s de cookies t\u00e9cnicas y funcionales: mantener nuestras herramientas (sitios web \/ aplicaciones \/ dispositivos) a salvo y seguras y garantizar que funcionen correctamente y mejoren continuamente.<\/li><li>Ofrecerle nuestro servicio de atenci\u00f3n al cliente.<\/li><\/ul><p>\u00a0<\/p><p>&#8211; En caso de que se formalice un contrato: realizar los servicios que nos solicita;<\/p><p>&#8211; El cumplimiento de obligaciones legales que conllevan un tratamiento de datos personales.<\/p><h3><strong>PERFILES<\/strong><\/h3><p>Cuando enviamos o mostramos comunicaciones o contenidos personalizados, podemos usar algunas t\u00e9cnicas calificadas como \u201celaboraci\u00f3n de perfiles\u201d (es decir, cualquier forma de tratamiento automatizado de datos personales que consiste en utilizar esos datos para evaluar ciertos aspectos personales de una persona f\u00edsica, en particular para analizar o predecir aspectos relacionados con las preferencias personales, intereses, ubicaci\u00f3n, u operativa que haya realizado con NEGOCAR EXCLUSIVE SLU). Esto significa que podemos recabar datos personales sobre usted para llevar a cabo esta elaboraci\u00f3n de perfiles. Centralizamos esta informaci\u00f3n y la analizamos para evaluar y predecir sus preferencias y \/ o intereses personales.En funci\u00f3n de nuestro an\u00e1lisis, enviamos o mostramos comunicaciones y \/ o contenidos adaptados a sus intereses \/ necesidades.<\/p><p>Ponemos en su conocimiento que tiene derecho a oponerse a que sus datos personales sean objeto de un tratamiento basado en la elaboraci\u00f3n de perfiles en ciertas circunstancias. A tal efecto, consulte la secci\u00f3n \u201cderechos del interesado y ejercicio\u201d.<\/p><h3><strong>\u00bfQUI\u00c9N PUEDE ACCEDER A SUS DATOS PERSONALES?<\/strong><\/h3><p><strong>5.1.<\/strong> Podemos compartir sus datos personales dentro del empresas asociadas a NEGOCAR EXCLUSIVE SLU.<\/p><p>Sus datos no podr\u00e1n ser cedidos\u00a0 a\u00a0 terceros a no ser que exista una la base legal del inter\u00e9s leg\u00edtimo.<\/p><p><strong>5.2.<\/strong> Sus datos personales tambi\u00e9n pueden ser tratados en nuestro nombre por nuestros proveedores terceros de confianza.<\/p><p>Suscribimos contratos con terceros de confianza para que realicen una variedad de servicios en nuestro nombre. S\u00f3lo les proporcionamos la informaci\u00f3n que necesitan para realizar el servicio, y les exigimos que no utilicen sus datos personales para ning\u00fan otro prop\u00f3sito. Siempre hacemos nuestro mayor esfuerzo para garantizar que todos los terceros con los que trabajamos mantengan la seguridad de los datos personales que les proporcionamos.<\/p><h3><strong>\u00bfCU\u00c1NTO TIEMPO CONSERVAMOS SUS DATOS PERSONALES?<\/strong><\/h3><p>Solo conservamos sus Datos Personales durante el tiempo que los necesitemos para el prop\u00f3sito o finalidad para el que han sido recabados con su consentimiento expreso, al objeto de satisfacer sus necesidades o para cumplir con nuestras obligaciones legales.<\/p><p>Para determinar el per\u00edodo de retenci\u00f3n de datos de sus Datos Personales, utilizamos los siguientes criterios:<\/p><ul><li>Datos Personales obtenidos al contactar con nosotros para una consulta o reclamaci\u00f3n: durante el tiempo necesario para atender su consulta;<\/li><li>Datos Personales obtenidos al prestar su consentimiento para el env\u00edo de comunicaciones o por ser necesarias de acuerdo con la normativa: hasta que se produzca el t\u00e9rmino de la finalidad para la que fueron requeridos.<\/li><\/ul><p>\u00a0<\/p><p>Cuando ya no necesitemos usar sus datos personales, se eliminar\u00e1n de nuestros sistemas y registros o se anonimizar\u00e1n para que ya no podamos identificarlos.<\/p><h3><strong>\u00bfSUS DATOS PERSONALES SE GUARDAN DE FORMA SEGURA?<\/strong><\/h3><p>Nos comprometemos a proteger sus Datos Personales y a tomar todas las precauciones razonables para hacerlo. Exigimos contractualmente que los terceros de confianza que manejan sus Datos Personales hagan lo mismo.<\/p><p>Siempre hacemos nuestro mejor esfuerzo para proteger sus Datos Personales y una vez que hemos recibido su informaci\u00f3n personal, utilizamos procedimientos estrictos y funciones de seguridad para tratar de evitar el acceso no autorizado.<\/p><h3><strong>DERECHOS DEL INTERESADO Y EJERCICIO<\/strong><\/h3><p>NEGOCAR EXCLUSIVE SLU respeta su derecho a la privacidad: es importante que usted tenga el control sobre sus datos de car\u00e1cter personal. En este sentido le informamos que le corresponden los siguientes derechos:<\/p><table width=\"500\"><tbody><tr><td>Derecho de Informaci\u00f3n<\/td><td>Tiene derecho a obtener informaci\u00f3n clara, transparente y f\u00e1cil de entender sobre la forma en que usamos sus datos personales y sobre sus derechos. Le facilitamos dicha informaci\u00f3n en esta Pol\u00edtica.<\/td><\/tr><tr><td>Derecho de acceso<\/td><td>Tiene derecho a acceder a los datos personales que tenemos de usted (con ciertos l\u00edmites).<br \/>Podremos cobrar una cantidad razonable, previo aviso, para cubrir los costes administrativos incurridos al facilitar la informaci\u00f3n.<br \/>Las solicitudes manifiestamente infundadas, excesivas o repetitivas podr\u00e1n no ser atendidas.<br \/>Para ejercer este derecho, puede ponerse en contacto con nosotros a trav\u00e9s de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho de rectificaci\u00f3n<\/td><td>Tiene derecho a hacer que se rectifiquen sus datos personales cuando sean inexactos o hayan dejado de ser v\u00e1lidos o a hacer que se completen cuando sean incompletos.<br \/>Para ejercer este derecho, puede ponerse en contacto con nosotros a trav\u00e9s de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho de supresi\u00f3n\/olvido<\/td><td>En determinados casos, le corresponde el derecho a hacer que sus datos personales sean borrados o eliminados. Es preciso se\u00f1alar que no se trata de un derecho absoluto, puesto que podremos tener motivos legales o leg\u00edtimos para conservarlos.<br \/>Si desea que suprimamos sus datos personales, puede ponerse en contacto con nosotros a trav\u00e9s de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho de oposici\u00f3n al marketing directo, incluida la elaboraci\u00f3n de perfiles<\/td><td>Puede darse de baja de nuestras comunicaciones de marketing directo en cualquier momento.<br \/>Puede darse de baja haciendo clic sobre el enlace \u201cDarse de baja\u201d en cualquier correo electr\u00f3nico comunicaci\u00f3n que le enviemos. De lo contrario, p\u00f3ngase en contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d.<br \/>Para oponerse a la elaboraci\u00f3n de perfiles, puede ponerse en contacto con nosotros a trav\u00e9s de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho a retirar el consentimiento en cualquier momento cuando el tratamiento de datos est\u00e9 basado en el consentimiento<\/td><td>Puede retirar su consentimiento al tratamiento de sus datos personales cuando el tratamiento est\u00e9 basado en su consentimiento. La retirada del consentimiento no afectar\u00e1 a la licitud del tratamiento basado en el consentimiento previo a su retirada. Para informarse de los casos en que el tratamiento est\u00e1 basado en el consentimiento, le remitimos al apartado \u201c\u00bfQu\u00e9 datos suyos recabamos?\u201d, \u201c\u00bfCu\u00e1l es la base legal para tratar sus Datos Personales?\u201d.<br \/>Si desea retirar su consentimiento, puede ponerse en contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho de oposici\u00f3n al tratamiento basado en la satisfacci\u00f3n de intereses leg\u00edtimos<\/td><td>Puede oponerse en cualquier momento a que tratemos sus datos cuando el tratamiento est\u00e9 basado en la satisfacci\u00f3n de intereses leg\u00edtimos. Para informarse de los casos en que el tratamiento est\u00e1 basado en intereses leg\u00edtimos, le remitimos al apartado \u201c\u00bfQu\u00e9 datos suyos recabamos?\u201d \u201c\u00bfCu\u00e1l es la base legal para tratar sus Datos Personales?\u201d.<br \/>Si desea ejercer este derecho, puede ponerse contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho a presentar una reclamaci\u00f3n ante una autoridad de control<\/td><td>Tiene derecho a reclamar ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos las pr\u00e1cticas de privacidad y protecci\u00f3n de datos.<p>\u00a0<\/p><p>No dude en ponerse en contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d antes de presentar una reclamaci\u00f3n ante la autoridad competente en materia de protecci\u00f3n de datos.<\/p><\/td><\/tr><tr><td>Derecho a la portabilidad de los datos<\/td><td>Tiene derecho a trasladar, copiar o transferir datos desde nuestra base de datos a otra distinta. Solo es posible ejercer este derecho con respecto a datos que haya facilitado, cuando el tratamiento est\u00e9 basado en la ejecuci\u00f3n de un contrato o en su consentimiento y el tratamiento se realice por medios automatizados. Para informarse de los casos en que el tratamiento est\u00e1 basado en contrato o en consentimiento, le remitimos al apartado \u201c\u00bfQu\u00e9 datos suyos recabamos?\u201d, \u201c\u00bfCu\u00e1l es la base legal para tratar sus Datos Personales?\u201d.<br \/>Para m\u00e1s informaci\u00f3n, puede ponerse en contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d.<\/td><\/tr><tr><td>Derecho de limitaci\u00f3n del tratamiento<\/td><td>Tiene derecho a solicitar la limitaci\u00f3n del tratamiento de sus datos. Si ejerce este derecho, el tratamiento de sus datos estar\u00e1 sujeto a limitaciones, por lo que podremos almacenarlos pero no podremos seguir us\u00e1ndolos ni trat\u00e1ndolos.Este derecho solo puede ejercerse en determinadas circunstancias definidas por el Reglamento General de Protecci\u00f3n de Datos, como sigue :<p>\u00a0<\/p><p>\u2013 que el interesado impugne la exactitud de los datos personales, durante el plazo que permita al responsable verificar la exactitud de los mismos;<\/p><p>\u2013 que el tratamiento sea il\u00edcito y el interesado se oponga a la supresi\u00f3n de los datos personales y solicite en su lugar la limitaci\u00f3n de su uso;<\/p><p>\u2013 que el responsable ya no necesite los datos personales para los fines del tratamiento, pero el interesado los necesite para la formulaci\u00f3n, el ejercicio o la defensa de reclamaciones;<\/p><p>\u2013 que el interesado se haya opuesto al tratamiento en virtud del art\u00edculo 21, apartado 1 del Reglamento (Derecho de oposici\u00f3n), mientras se verifica si los motivos leg\u00edtimos del responsable prevalecen sobre los del interesado.<\/p><p>Si desea ejercer este derecho, puede ponerse en contacto con nosotros por cualquiera de los medios indicados en \u201cContacto\u201d.<\/p><\/td><\/tr><\/tbody><\/table><h3><strong>CONTACTO:<\/strong><\/h3><p>Si tiene cualquier duda acerca de la forma en que tratamos y usamos sus datos personales o desea ejercer cualquiera de los derechos previstos, puede comunic\u00e1rnoslo enviando un correo electr\u00f3nico a info@specialcarslasramblas.eso bien escribi\u00e9ndonos a la siguiente direcci\u00f3n: Antonio Mar\u00eda Manrique n\u00ba 26en Las Palmas de G.C.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edticas De Privacidad Inicio Pol\u00edticas De Privacidad La presente \u201cPol\u00edtica de Privacidad\u201d recoge las reglas que rigen la recogida y tratamiento de datos personales por parte de NEGOCAR EXCLUSIVE SLU y garantiza que estas labores de recogida y tratamiento de datos cumplir\u00e1, en todo momento, cumpliendo en materia de protecci\u00f3n de datos de car\u00e1cter personal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-98","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/pages\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":16,"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/pages\/98\/revisions"}],"predecessor-version":[{"id":493,"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/pages\/98\/revisions\/493"}],"wp:attachment":[{"href":"https:\/\/campermax.websmwinner.com\/fr\/wp-json\/wp\/v2\/media?parent=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}